{"id":25697,"date":"2026-03-24T12:20:38","date_gmt":"2026-03-24T10:20:38","guid":{"rendered":"https:\/\/www.fagor.eus\/?p=25697"},"modified":"2026-03-25T16:49:10","modified_gmt":"2026-03-25T14:49:10","slug":"el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social","status":"publish","type":"post","link":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/","title":{"rendered":"El a\u00f1o pasado Fagor destin\u00f3 3,1 millones de euros a diferentes proyectos confirmando su compromiso social"},"content":{"rendered":"<p>En 2025 <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.fagor.eus\/es\/\">Fagor<\/a><\/span> volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales, de la cual la mayor parte, 1,8 millones de euros, se qued\u00f3 en Debagoiena (Gipuzkoa), donde se encuentran las principales sedes de las cooperativas del Grupo. Asimismo, Fagor impuls\u00f3 iniciativas dirigidas a su comunidad (810.000 euros), agentes de solidaridad internacional (314.000 euros) y proyectos gestados en el Pa\u00eds Vasco (144.000 euros). El grupo cooperativo volvi\u00f3 a superar el porcentaje del 10% que marca la ley, destinando a su fondo social el 12% de los beneficios anuales.<\/p>\n<p>Aritz Otxandiano Kanpo, responsable de Sostenibilidad del Grupo Fagor, ha querido poner el foco en el compromiso que Fagor tiene con la comunidad y el territorio: \u201cSomos un grupo cooperativo, por ello, es fundamental y l\u00f3gico mantener un claro compromiso comunitario. Seguimos siendo un Grupo comprometido, apoyamos distintas iniciativas y somos agente activo en varias de ellas. Queremos colaborar en las din\u00e1micas que a\u00f1o tras a\u00f1o se impulsan para dar respuestas adecuadas a distintos retos sociales. Lo hacemos desde la intercooperaci\u00f3n, pues sabemos que a largo plazo nos ayudar\u00e1 a obtener mejores resultados\u201d.<\/p>\n<p><strong>La mayor parte, en Debagoiena<\/strong><\/p>\n<p>La mayor parte del fondo social de Fagor se qued\u00f3 en Debagoiena \u2014el 59% de las ayudas\u2014. Entre otras iniciativas, el grupo cooperativo impuls\u00f3 proyectos creados en el marco de la red de sostenibilidad <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/debagoiena2030.eus\/es\/\">Debagoiena 2030<\/a><\/span> (785.000 euros), tales como distintas comunidades energ\u00e9ticas \u2014se convirti\u00f3 en socio colaborador de la cooperativa <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/esnargi.eus\/es\/\">Esnargi<\/a><\/span>, de Eskoriatza\u2014, la iniciativa que pretende impulsar la soberan\u00eda alimentaria de Debagoiena <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/tokixan.eus\/\">Tokixan<\/a><\/span> y el proyecto <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/plazabizi.eus\/es\/\"><em>Plaza Bizi<\/em><\/a><\/span> que trabaja por una movilidad sostenible en la zona Arima Zubi de Arrasate. Asimismo, Fagor volvi\u00f3 a hacer aportaciones significativas a diferentes agentes e infraestructuras educativas (785.000 euros). Entre ellas se encuentran el centro de innovaci\u00f3n y emprendimiento para una transformaci\u00f3n industrial sostenible <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.mondragon.edu\/es\/escuela-politecnica-superior\/emprendimiento-tecnologico\/hirekin\">Hirekin<\/a><\/span>, el proyecto <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/arizmendi.eus\/almen\/\"><em>Torrebaso 2030<\/em><\/a><\/span> de la ikastola Arizmendi y el centro <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/kolaborategia.mondragon.edu\/es\/inicio\">Kolaborategia<\/a><\/span> de Huhezi (Mondragon Unibertsitatea). Adem\u00e1s, las cooperativas de Fagor destinaron un total de 251.000 euros a asociaciones locales.<\/p>\n<p>Por otra parte, Fagor impuls\u00f3 distintos proyectos internos: los planes de euskera de las cooperativas, la iniciativa para impulsar la movilidad sostenible de camino al trabajo Fagor Mugi y el programa que busca que personas del colectivo se impliquen en proyectos sociales Fagor Elkarrekin. Concretamente, el grupo cooperativo destin\u00f3 753.000 euros a los planes de euskera de las cooperativas. \u201cEl compromiso ratificado a\u00f1o tras a\u00f1o ha convertido a Fagor en un agente referente en varios \u00e1mbitos. Esto demuestra que las iniciativas y din\u00e1micas internas pueden verse reflejadas y tener su efecto en la sociedad. Fagor cuenta con una amplia comunidad\u201d, explica el responsable de Sostenibilidad.<\/p>\n<p><strong>Pa\u00eds Vasco y solidaridad internacional<\/strong><\/p>\n<p>M\u00e1s all\u00e1 de Debagoiena o la comunidad de Fagor, el grupo cooperativo ayud\u00f3 otras iniciativas gestadas en el Pa\u00eds Vasco \u2014destin\u00f3 144.000 euros, la mayor parte, 120.000 euros, a trav\u00e9s del programa de cooperaci\u00f3n <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.fagor.eus\/es\/fondo-social\/fagor-herrigintza\/\">Fagor Herrigintza<\/a><\/span>\u2014, y mantuvo su solidaridad internacional destinando un total de 314.000 euros \u2014la <span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/mundukide.org\/es\/\">Fundaci\u00f3n Mundukide<\/a><\/span>, la cual promueve el desarrollo comunitario de los pa\u00edses en v\u00edas de desarrollo, recibi\u00f3 304.000 euros\u2014.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales, de la cual la mayor parte, 1,8 millones de&#8230;<\/p>\n","protected":false},"author":4,"featured_media":25726,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104],"tags":[],"class_list":{"0":"post-25697","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-grupo-fagor-es"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor<\/title>\n<meta name=\"description\" content=\"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor\" \/>\n<meta property=\"og:description\" content=\"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/\" \/>\n<meta property=\"og:site_name\" content=\"FAGOR\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-24T10:20:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T14:49:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2-1024x682.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"komunikazioa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@system\" \/>\n<meta name=\"twitter:site\" content=\"@FagorTaldea\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"komunikazioa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/\"},\"author\":{\"name\":\"komunikazioa\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\"},\"headline\":\"El a\u00f1o pasado Fagor destin\u00f3 3,1 millones de euros a diferentes proyectos confirmando su compromiso social\",\"datePublished\":\"2026-03-24T10:20:38+00:00\",\"dateModified\":\"2026-03-25T14:49:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/\"},\"wordCount\":534,\"image\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png\",\"articleSection\":[\"Grupo Fagor\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/\",\"name\":\"Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png\",\"datePublished\":\"2026-03-24T10:20:38+00:00\",\"dateModified\":\"2026-03-25T14:49:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\"},\"description\":\"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png\",\"contentUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El a\u00f1o pasado Fagor destin\u00f3 3,1 millones de euros a diferentes proyectos confirmando su compromiso social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#website\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/\",\"name\":\"Fagor\",\"description\":\"Trabajando por un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fagor.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\",\"name\":\"komunikazioa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"caption\":\"komunikazioa\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/system\"],\"url\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/author\\\/komunikazioa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor","description":"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/","og_locale":"es_ES","og_type":"article","og_title":"Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor","og_description":"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.","og_url":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/","og_site_name":"FAGOR","article_published_time":"2026-03-24T10:20:38+00:00","article_modified_time":"2026-03-25T14:49:10+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2-1024x682.png","type":"image\/png"}],"author":"komunikazioa","twitter_card":"summary_large_image","twitter_creator":"@system","twitter_site":"@FagorTaldea","twitter_misc":{"Escrito por":"komunikazioa","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#article","isPartOf":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/"},"author":{"name":"komunikazioa","@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f"},"headline":"El a\u00f1o pasado Fagor destin\u00f3 3,1 millones de euros a diferentes proyectos confirmando su compromiso social","datePublished":"2026-03-24T10:20:38+00:00","dateModified":"2026-03-25T14:49:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/"},"wordCount":534,"image":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png","articleSection":["Grupo Fagor"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/","url":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/","name":"Fagor destin\u00f3 3,1 millones de euros a proyectos sociales &#187; Grupo Fagor","isPartOf":{"@id":"https:\/\/www.fagor.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#primaryimage"},"image":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png","datePublished":"2026-03-24T10:20:38+00:00","dateModified":"2026-03-25T14:49:10+00:00","author":{"@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f"},"description":"En 2025 Fagor volvi\u00f3 a confirmar su compromiso social destinando un total de 3,1 millones de euros a diferentes proyectos sociales.","breadcrumb":{"@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#primaryimage","url":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png","contentUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2026\/03\/FAGOR-gizarte-funtsa-eta-Plazabizi-2025-2.png","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/www.fagor.eus\/es\/el-ano-pasado-fagor-destino-31-millones-de-euros-a-diferentes-proyectos-confirmando-su-compromiso-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fagor.eus\/es\/"},{"@type":"ListItem","position":2,"name":"El a\u00f1o pasado Fagor destin\u00f3 3,1 millones de euros a diferentes proyectos confirmando su compromiso social"}]},{"@type":"WebSite","@id":"https:\/\/www.fagor.eus\/#website","url":"https:\/\/www.fagor.eus\/","name":"Fagor","description":"Trabajando por un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fagor.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f","name":"komunikazioa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","caption":"komunikazioa"},"sameAs":["https:\/\/x.com\/system"],"url":"https:\/\/www.fagor.eus\/es\/author\/komunikazioa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/25697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/comments?post=25697"}],"version-history":[{"count":3,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/25697\/revisions"}],"predecessor-version":[{"id":25741,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/25697\/revisions\/25741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/media\/25726"}],"wp:attachment":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/media?parent=25697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/categories?post=25697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/tags?post=25697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}