{"id":15197,"date":"2023-01-03T13:55:35","date_gmt":"2023-01-03T13:55:35","guid":{"rendered":"https:\/\/www.fagor.eus\/?p=15197"},"modified":"2023-02-21T15:59:43","modified_gmt":"2023-02-21T15:59:43","slug":"la-participacion-de-las-mujeres-clave-para-el-futuro-steam","status":"publish","type":"post","link":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/","title":{"rendered":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM"},"content":{"rendered":"<p>Los retos y las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas) y, para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a impulsar diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.<\/p>\n<p>En definitiva, la tasa de natalidad ha sufrido un descenso considerable estos \u00faltimos a\u00f1os, y eso ha producido un descenso en el n\u00famero de personas que cursan el bachillerato cient\u00edfico-tecnol\u00f3gico bio-sanitario, pues aun manteniendo el porcentaje de personas que lo cursan, se reduce el n\u00famero de alumnos y alumnas debido al descenso de la tasa de natalidad. De hecho, seg\u00fan un estudio publicado por el Instituto Vasco de Estad\u00edstica Eustat, para el 2030, el n\u00famero de alumnos y alumnas de los centros educativos sufrir\u00e1 un descenso del 10%.<\/p>\n<p>Entre otras cuestiones, diversos estudios han corroborado que los estudios cient\u00edfico-tecnol\u00f3gicos tienen dificultades para captar el inter\u00e9s de las personas j\u00f3venes. Ello se debe, entre otros factores, a c\u00f3mo percibe la sociedad dicho \u00e1mbito de estudio: percepci\u00f3n de dificultad, existencia de profesiones abstractas y desconocidas, sensaci\u00f3n de inaccesibilidad, falta de una oferta atractiva, etc. Precisamente, seg\u00fan ha publicado Eustat, desde 2016 el n\u00famero de matriculaciones ha sufrido un descenso del 16%; y las mujeres siguen siendo minor\u00eda. En Mondragon Unibertsitatea, por ejemplo, en 2021, las mujeres representaban el 27% de las personas matriculadas en los grados STEAM, de los cuales fueron los grados de Ingenier\u00eda Mecatr\u00f3nica (6%), Ingenier\u00eda Electr\u00f3nica (16%), Ingenier\u00eda Energ\u00e9tica (17%), Ingenier\u00eda Mec\u00e1nica (19%) e Ingenier\u00eda Inform\u00e1tica (21%) los que presentaron un menor n\u00famero de mujeres.<\/p>\n<p><strong>Una oportunidad de futuro<\/strong><\/p>\n<p>Las cooperativas del Grupo Fagor trabajan con el objetivo de atraer el talento, ya que son conscientes de que el tejido cooperativo creado y arraigado en Debagoiena (Gipuzkoa) necesita de personas preparadas para el futuro profesional. Ello permitir\u00eda, entre otras cuestiones, mantener a Debagoiena como territorio referente en la transformaci\u00f3n social, el fortalecimiento comunitario y la competitividad, desarrollando siempre modelos propios de hacer empresa.<\/p>\n<p>Susana Soto Iglesias, responsable de Ingenier\u00eda del Negocio Solar de Mondragon Assembly, subraya la importancia de trabajar para que las personas j\u00f3venes perciban a las cooperativas locales como oportunidades de futuro: \u00abDebemos desarrollar instrumentos que ayuden a que las personas j\u00f3venes conozcan nuestras cooperativas. Deben saber que pueden construir su propio futuro, y que ser\u00e1n claves para fortalecer y desarrollar nuestras redes cooperativas. Nuestras principales plantas se encuentran en Debagoiena, y trabajamos a nivel mundial. Somos referentes en nuestros sectores. Necesitamos personas formadas para seguir trabajando por la competitividad y abordar adecuadamente los retos planteados por el presente y el futuro\u00bb.<\/p>\n<p><strong>La importancia de las mujeres<\/strong><\/p>\n<p>La labor que tanto las cooperativas como los centros educativos est\u00e1n desarrollando para atraer el talento se centra especialmente en las mujeres. \u00abLa tasa de natalidad y los datos de matriculaci\u00f3n disminuyen, y las mujeres siguen siendo minor\u00eda en las matriculaciones de los estudios del \u00e1mbito STEAM. No podemos olvidar que las mujeres representan a la mitad de la sociedad, por lo que son imprescindibles para revertir la situaci\u00f3n\u00bb, explica Maite Anaya Rodr\u00edguez, coordinadora de Orientaci\u00f3n de la Escuela Superior de Mondragon.<\/p>\n<p>Por su parte, Oihana Jausoro Agirre, experta en el \u00e1mbito de la Igualdad de G\u00e9nero y trabajadora de la cooperativa Emun, habla sobre las razones de la \u00abbaja representaci\u00f3n\u00bb de las mujeres en estudios y puestos de trabajo del \u00e1mbito STEAM: \u00abA\u00fan existen muchos perjuicios de g\u00e9nero. Culturalmente, la educaci\u00f3n y el papel de las mujeres han estado ligados al hogar o al cuidado de personas, y aunque hoy en d\u00eda tenemos referentes claros del \u00e1mbito STEAM, las mujeres siguen siendo minor\u00eda en las matriculaciones. Debemos reforzar nuestra presencia en dicho \u00e1mbito\u201d.<\/p>\n<p>Por otro lado, en palabras de personas expertas en la materia, es importante dar visibilidad a las mujeres que trabajan en el \u00e1mbito STEAM, \u00abpara que las j\u00f3venes de hoy en d\u00eda tengan referentes\u00bb y sean conscientes del papel fundamental que varias mujeres han tenido en hallazgos relacionados con la ciencia, la tecnolog\u00eda, la ingenier\u00eda y las matem\u00e1ticas. Entre ellas se encuentran Ada Lovelace (1815- 1852), fundadora del primer algoritmo; Hedy Lamarr (1914-2000), creadora de la tecnolog\u00eda wifi; Mildred Dresselhaus (1930-2017), participante en la elaboraci\u00f3n de la aplicaci\u00f3n de carbono; Rose Dieng-Kuntz (1596-2008), colaboradora en los primeros pasos de la red de internet\u2026<\/p>\n<p>Y tambi\u00e9n hay ejemplos locales, como por ejemplo Marta Macho Stadler, matem\u00e1tica, profesora y divulgadora cient\u00edfica; Jone Uria Albizuri, matem\u00e1tica y <em>bertsolari<\/em>; y Nerea Pagaldai Agiriano, bi\u00f3loga y especializada en el comportamiento animal. Adem\u00e1s, no hay que olvidarse de todas esas mujeres que trabajan en cooperativas del Grupo Fagor, y que, seg\u00fan Gema Mancebo Migu\u00e9lez, responsable de Recursos Humanos de Fagor Professional, act\u00faan con \u00abalta autoexigencia y precisi\u00f3n\u00bb, lo que supone un \u00abaumento del rendimiento\u00bb.<\/p>\n<p><strong>STEAM, competitividad y sostenibilidad<\/strong><\/p>\n<p>El objetivo de reforzar y atraer talento del \u00e1mbito STEAM tiene que ver en gran medida con los retos que hoy d\u00eda se le plantean a la sociedad. \u00abLa sociedad y la industria est\u00e1n inmersas en una profunda transformaci\u00f3n. Los \u00e1mbitos STEAM son imprescindibles para construir un entorno sostenible y competitivo. Asimismo, dichos \u00e1mbitos ayudan a desarrollar un trabajo de calidad y contribuyen en el enriquecimiento y bienestar de la sociedad\u00bb, reconoce la responsable de Recursos Humanos de Fagor Professional.<\/p>\n<p>Por ello, el n\u00famero de puestos de trabajo del \u00e1mbito STEAM va en aumento. As\u00ed lo corrobora la responsable de Ingenier\u00eda del Negocio Solar de Mondragon Assembly: \u201cEl n\u00famero de personas que ocupan puestos STEAM ha aumentado considerablemente. Adem\u00e1s, dicho perfil est\u00e1 muy presentes en todo el proceso productivo\u00bb. Eso s\u00ed, reconoce que la presencia de mujeres sigue siendo \u00abmuy escasa\u00bb.<\/p>\n<p>Por su parte, el Grupo Fagor ha comenzado a trabajar para dar a conocer su tejido industrial y las oportunidades profesionales. Entre otras, las cooperativas del Grupo ofrecen diversos programas relacionados con el periodo de pr\u00e1cticas de alumnos y alumnas. Zuri\u00f1e Garitaonandia Beatove, estudiante del m\u00e1ster de Ingenier\u00eda Industrial de MU, por ejemplo, desarrolla su periodo de pr\u00e1cticas en Fagor Automation, y agradece el esfuerzo realizado por la cooperativa para atraer al alumnado del \u00e1mbito STEAM: \u00abLa oportunidad de desarrollar el periodo de pr\u00e1cticas en una empresa como Fagor Automation, la apuesta realizada por la cooperativa, el dejarnos ser parte de su d\u00eda a d\u00eda, refuerza nuestra convicci\u00f3n. Nos motiva. Nos ayuda a confirmar que la elecci\u00f3n hecha en su d\u00eda por el \u00e1mbito STEAM fue la correcta\u00bb.<\/p>\n<p><strong>Mondragon ZTIM HUB, instrumento para impulsar la vocaci\u00f3n STEAM<\/strong><\/p>\n<p>Mondragon ZTIM HUB, iniciativa presentada recientemente en Debagoiena, pretende crear un tejido educativo estable a trav\u00e9s de la colaboraci\u00f3n entre centros educativos, empresas, agentes sociales y ayuntamientos -el Grupo Fagor participa en dicha iniciativa-. Dentro de este marco, queriendo conocer las tendencias educativas de las personas de entre 14 y 16 a\u00f1os de la comarca, en 2021, Mondragon Unibertsitatea (MU) inici\u00f3 un estudio conjunto con Elhuyar.<\/p>\n<p>Seg\u00fan este estudio, el 47,2% de los chicos y el 23,8% de las chicas estar\u00edan interesadas e interesados en trabajar en puestos de trabajo del \u00e1mbito STEAM.\u00a0Por ello, el estudio propone, entre otras cuestiones, trabajar por la visibilidad de las alumnas y trabajadoras, investigadoras o cient\u00edficas del \u00e1mbito; y habla de una orientaci\u00f3n sin prejuicios de g\u00e9nero, intervenir en actividades STEAM e incidir en proyectos educativos de los centros.<\/p>\n<p>Mondragon ZTIM HUB ya ha comenzado a impulsar iniciativas para revertir la situaci\u00f3n. Por ejemplo, ha puesto en marcha retos tem\u00e1ticos, con los que se pretende impulsar un modelo educativo basado en tener que afrontar diversos retos: el alumnado de la ESO debe abordar diversas situaciones y problemas que se le plantean, desarrollando as\u00ed competencias t\u00e9cnicas y transversales propias de cada nivel de estudio, que incluyen autonom\u00eda en el aprendizaje, trabajo en equipo\u2026 Dicho proceso cuenta con el apoyo de empresas como Fagor Electr\u00f3nica y Mondragon Assembly quienes se encargan de ofrecer p\u00edldoras informativas, visitas a empresas, charlas, etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los retos y las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas) y, para ello,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":15198,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[],"class_list":{"0":"post-15197","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-qr"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor<\/title>\n<meta name=\"description\" content=\"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor\" \/>\n<meta property=\"og:description\" content=\"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/\" \/>\n<meta property=\"og:site_name\" content=\"FAGOR\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-03T13:55:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T15:59:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"komunikazioa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@system\" \/>\n<meta name=\"twitter:site\" content=\"@FagorTaldea\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"komunikazioa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/\"},\"author\":{\"name\":\"komunikazioa\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\"},\"headline\":\"La participaci\u00f3n de las mujeres, clave para el futuro STEAM\",\"datePublished\":\"2023-01-03T13:55:35+00:00\",\"dateModified\":\"2023-02-21T15:59:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/\"},\"wordCount\":1418,\"image\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/STEAM-Grupo-Fagor.jpg\",\"articleSection\":[\"QR\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/\",\"name\":\"La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/STEAM-Grupo-Fagor.jpg\",\"datePublished\":\"2023-01-03T13:55:35+00:00\",\"dateModified\":\"2023-02-21T15:59:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\"},\"description\":\"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/STEAM-Grupo-Fagor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fagor.eus\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/STEAM-Grupo-Fagor.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"STEAM-Grupo Fagor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La participaci\u00f3n de las mujeres, clave para el futuro STEAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#website\",\"url\":\"https:\\\/\\\/www.fagor.eus\\\/\",\"name\":\"Fagor\",\"description\":\"Trabajando por un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fagor.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fagor.eus\\\/#\\\/schema\\\/person\\\/e09b7878906ad616c343aa3e5a83bc2f\",\"name\":\"komunikazioa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g\",\"caption\":\"komunikazioa\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/system\"],\"url\":\"https:\\\/\\\/www.fagor.eus\\\/es\\\/author\\\/komunikazioa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor","description":"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/","og_locale":"es_ES","og_type":"article","og_title":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor","og_description":"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.","og_url":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/","og_site_name":"FAGOR","article_published_time":"2023-01-03T13:55:35+00:00","article_modified_time":"2023-02-21T15:59:43+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg","type":"image\/jpeg"}],"author":"komunikazioa","twitter_card":"summary_large_image","twitter_creator":"@system","twitter_site":"@FagorTaldea","twitter_misc":{"Escrito por":"komunikazioa","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#article","isPartOf":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/"},"author":{"name":"komunikazioa","@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f"},"headline":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM","datePublished":"2023-01-03T13:55:35+00:00","dateModified":"2023-02-21T15:59:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/"},"wordCount":1418,"image":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg","articleSection":["QR"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/","url":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/","name":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM &#187; Grupo Fagor","isPartOf":{"@id":"https:\/\/www.fagor.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#primaryimage"},"image":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg","datePublished":"2023-01-03T13:55:35+00:00","dateModified":"2023-02-21T15:59:43+00:00","author":{"@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f"},"description":"Tanto los retos como las previsiones de los pr\u00f3ximos a\u00f1os obligan a profundizar en los estudios y puestos de trabajo STEAM (acr\u00f3nimo de Ciencia, Tecnolog\u00eda, Ingenier\u00eda y Matem\u00e1ticas). Para ello, es fundamental despertar el inter\u00e9s del alumnado. Conscientes de ello, las empresas han comenzado a trabajar impulsando diversas iniciativas para atraer talento. El Grupo Fagor no es una excepci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#primaryimage","url":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg","contentUrl":"https:\/\/www.fagor.eus\/wp-content\/uploads\/2023\/01\/STEAM-Grupo-Fagor.jpg","width":2000,"height":1333,"caption":"STEAM-Grupo Fagor"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fagor.eus\/es\/la-participacion-de-las-mujeres-clave-para-el-futuro-steam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fagor.eus\/es\/"},{"@type":"ListItem","position":2,"name":"La participaci\u00f3n de las mujeres, clave para el futuro STEAM"}]},{"@type":"WebSite","@id":"https:\/\/www.fagor.eus\/#website","url":"https:\/\/www.fagor.eus\/","name":"Fagor","description":"Trabajando por un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fagor.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fagor.eus\/#\/schema\/person\/e09b7878906ad616c343aa3e5a83bc2f","name":"komunikazioa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c624a67c23ed6ff6fd4111959b9a1001016b57c6bebaecbec025adcaa081e6e?s=96&d=mm&r=g","caption":"komunikazioa"},"sameAs":["https:\/\/x.com\/system"],"url":"https:\/\/www.fagor.eus\/es\/author\/komunikazioa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/15197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/comments?post=15197"}],"version-history":[{"count":9,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/15197\/revisions"}],"predecessor-version":[{"id":15564,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/posts\/15197\/revisions\/15564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/media\/15198"}],"wp:attachment":[{"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/media?parent=15197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/categories?post=15197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fagor.eus\/es\/wp-json\/wp\/v2\/tags?post=15197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}